{"id":485257,"date":"2023-07-27T14:10:32","date_gmt":"2023-07-27T11:10:32","guid":{"rendered":"https:\/\/snir.dreamax.co.il\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/"},"modified":"2026-01-20T14:27:51","modified_gmt":"2026-01-20T11:27:51","slug":"%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99","status":"publish","type":"product","link":"https:\/\/meircohenltd.com\/js\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/","title":{"rendered":"\u05e1\u05d8 \u05d8\u05dc\u05d9\u05ea \u05d1\u05d3\u05d9\u05dd \u05de\u05d2\u05d5\u05d5\u05e0\u05d9\u05dd \u05e4\u05e8\u05d7\u05d5\u05e0\u05d9"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":443919,"template":"","meta":[],"product_brand":[],"product_cat":[2630,2596],"product_tag":[],"class_list":{"0":"post-485257","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-2630","7":"product_cat-2596","8":"pa_color-2178","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u05e1\u05d8 \u05d8\u05dc\u05d9\u05ea \u05d1\u05d3\u05d9\u05dd \u05de\u05d2\u05d5\u05d5\u05e0\u05d9\u05dd \u05e4\u05e8\u05d7\u05d5\u05e0\u05d9 - \u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05de\u05d5\u05e8\u05d5\u05ea \u05dc\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df \u05d1\u05e2&quot;\u05de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meircohenltd.com\/product\/\u05e1\u05d8-\u05d8\u05dc\u05d9\u05ea-\u05d1\u05d3\u05d9\u05dd-\u05de\u05d2\u05d5\u05d5\u05e0\u05d9\u05dd-\u05e4\u05e8\u05d7\u05d5\u05e0\u05d9\/\" \/>\n<meta property=\"og:locale\" content=\"he_IL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u05e1\u05d8 \u05d8\u05dc\u05d9\u05ea \u05d1\u05d3\u05d9\u05dd \u05de\u05d2\u05d5\u05d5\u05e0\u05d9\u05dd \u05e4\u05e8\u05d7\u05d5\u05e0\u05d9 - \u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05de\u05d5\u05e8\u05d5\u05ea \u05dc\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df \u05d1\u05e2&quot;\u05de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meircohenltd.com\/product\/\u05e1\u05d8-\u05d8\u05dc\u05d9\u05ea-\u05d1\u05d3\u05d9\u05dd-\u05de\u05d2\u05d5\u05d5\u05e0\u05d9\u05dd-\u05e4\u05e8\u05d7\u05d5\u05e0\u05d9\/\" \/>\n<meta property=\"og:site_name\" content=\"\u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05de\u05d5\u05e8\u05d5\u05ea \u05dc\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df \u05d1\u05e2&quot;\u05de\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-20T11:27:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meircohenltd.com\/wp-content\/uploads\/integration_images\/EMTAP3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u05d6\u05de\u05df \u05e7\u05e8\u05d9\u05d0\u05d4 \u05de\u05d5\u05e2\u05e8\u05da\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05d3\u05e7\u05d41\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/\",\"url\":\"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/\",\"name\":\"\u05e1\u05d8 \u05d8\u05dc\u05d9\u05ea \u05d1\u05d3\u05d9\u05dd \u05de\u05d2\u05d5\u05d5\u05e0\u05d9\u05dd \u05e4\u05e8\u05d7\u05d5\u05e0\u05d9 - \u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05de\u05d5\u05e8\u05d5\u05ea \u05dc\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df \u05d1\u05e2&quot;\u05de\",\"isPartOf\":{\"@id\":\"https:\/\/meircohenltd.com\/wc\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/meircohenltd.com\/wp-content\/uploads\/integration_images\/EMTAP3.jpg\",\"datePublished\":\"2023-07-27T11:10:32+00:00\",\"dateModified\":\"2026-01-20T11:27:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/#breadcrumb\"},\"inLanguage\":\"he-IL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"he-IL\",\"@id\":\"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/#primaryimage\",\"url\":\"https:\/\/meircohenltd.com\/wp-content\/uploads\/integration_images\/EMTAP3.jpg\",\"contentUrl\":\"https:\/\/meircohenltd.com\/wp-content\/uploads\/integration_images\/EMTAP3.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\/\/meircohenltd.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u05d7\u05e0\u05d5\u05ea\",\"item\":\"https:\/\/meircohenltd.com\/wc\/%d7%97%d7%a0%d7%95%d7%aa\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u05e1\u05d8 \u05d8\u05dc\u05d9\u05ea \u05d1\u05d3\u05d9\u05dd \u05de\u05d2\u05d5\u05d5\u05e0\u05d9\u05dd \u05e4\u05e8\u05d7\u05d5\u05e0\u05d9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/meircohenltd.com\/wc\/#website\",\"url\":\"https:\/\/meircohenltd.com\/wc\/\",\"name\":\"\u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05de\u05d5\u05e8\u05d5\u05ea \u05dc\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df \u05d1\u05e2&quot;\u05de\",\"description\":\"\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df\",\"publisher\":{\"@id\":\"https:\/\/meircohenltd.com\/wc\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/meircohenltd.com\/wc\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"he-IL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/meircohenltd.com\/wc\/#organization\",\"name\":\"\u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05de\u05d5\u05e8\u05d5\u05ea \u05dc\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df \u05d1\u05e2&quot;\u05de\",\"url\":\"https:\/\/meircohenltd.com\/wc\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"he-IL\",\"@id\":\"https:\/\/meircohenltd.com\/wc\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/meircohenltd.com\/wp-content\/uploads\/2023\/07\/logo.svg\",\"contentUrl\":\"https:\/\/meircohenltd.com\/wp-content\/uploads\/2023\/07\/logo.svg\",\"width\":605,\"height\":429,\"caption\":\"\u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05de\u05d5\u05e8\u05d5\u05ea \u05dc\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df \u05d1\u05e2&quot;\u05de\"},\"image\":{\"@id\":\"https:\/\/meircohenltd.com\/wc\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u05e1\u05d8 \u05d8\u05dc\u05d9\u05ea \u05d1\u05d3\u05d9\u05dd \u05de\u05d2\u05d5\u05d5\u05e0\u05d9\u05dd \u05e4\u05e8\u05d7\u05d5\u05e0\u05d9 - \u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05de\u05d5\u05e8\u05d5\u05ea \u05dc\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df \u05d1\u05e2&quot;\u05de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meircohenltd.com\/product\/\u05e1\u05d8-\u05d8\u05dc\u05d9\u05ea-\u05d1\u05d3\u05d9\u05dd-\u05de\u05d2\u05d5\u05d5\u05e0\u05d9\u05dd-\u05e4\u05e8\u05d7\u05d5\u05e0\u05d9\/","og_locale":"he_IL","og_type":"article","og_title":"\u05e1\u05d8 \u05d8\u05dc\u05d9\u05ea \u05d1\u05d3\u05d9\u05dd \u05de\u05d2\u05d5\u05d5\u05e0\u05d9\u05dd \u05e4\u05e8\u05d7\u05d5\u05e0\u05d9 - \u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05de\u05d5\u05e8\u05d5\u05ea \u05dc\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df \u05d1\u05e2&quot;\u05de","og_url":"https:\/\/meircohenltd.com\/product\/\u05e1\u05d8-\u05d8\u05dc\u05d9\u05ea-\u05d1\u05d3\u05d9\u05dd-\u05de\u05d2\u05d5\u05d5\u05e0\u05d9\u05dd-\u05e4\u05e8\u05d7\u05d5\u05e0\u05d9\/","og_site_name":"\u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05de\u05d5\u05e8\u05d5\u05ea \u05dc\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df \u05d1\u05e2&quot;\u05de","article_modified_time":"2026-01-20T11:27:51+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/meircohenltd.com\/wp-content\/uploads\/integration_images\/EMTAP3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u05d6\u05de\u05df \u05e7\u05e8\u05d9\u05d0\u05d4 \u05de\u05d5\u05e2\u05e8\u05da":"\u05d3\u05e7\u05d41"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/","url":"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/","name":"\u05e1\u05d8 \u05d8\u05dc\u05d9\u05ea \u05d1\u05d3\u05d9\u05dd \u05de\u05d2\u05d5\u05d5\u05e0\u05d9\u05dd \u05e4\u05e8\u05d7\u05d5\u05e0\u05d9 - \u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05de\u05d5\u05e8\u05d5\u05ea \u05dc\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df \u05d1\u05e2&quot;\u05de","isPartOf":{"@id":"https:\/\/meircohenltd.com\/wc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/#primaryimage"},"image":{"@id":"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/#primaryimage"},"thumbnailUrl":"https:\/\/meircohenltd.com\/wp-content\/uploads\/integration_images\/EMTAP3.jpg","datePublished":"2023-07-27T11:10:32+00:00","dateModified":"2026-01-20T11:27:51+00:00","breadcrumb":{"@id":"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/#breadcrumb"},"inLanguage":"he-IL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/"]}]},{"@type":"ImageObject","inLanguage":"he-IL","@id":"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/#primaryimage","url":"https:\/\/meircohenltd.com\/wp-content\/uploads\/integration_images\/EMTAP3.jpg","contentUrl":"https:\/\/meircohenltd.com\/wp-content\/uploads\/integration_images\/EMTAP3.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/meircohenltd.com\/product\/%d7%a1%d7%98-%d7%98%d7%9c%d7%99%d7%aa-%d7%91%d7%93%d7%99%d7%9d-%d7%9e%d7%92%d7%95%d7%95%d7%a0%d7%99%d7%9d-%d7%a4%d7%a8%d7%97%d7%95%d7%a0%d7%99\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/meircohenltd.com\/"},{"@type":"ListItem","position":2,"name":"\u05d7\u05e0\u05d5\u05ea","item":"https:\/\/meircohenltd.com\/wc\/%d7%97%d7%a0%d7%95%d7%aa\/"},{"@type":"ListItem","position":3,"name":"\u05e1\u05d8 \u05d8\u05dc\u05d9\u05ea \u05d1\u05d3\u05d9\u05dd \u05de\u05d2\u05d5\u05d5\u05e0\u05d9\u05dd \u05e4\u05e8\u05d7\u05d5\u05e0\u05d9"}]},{"@type":"WebSite","@id":"https:\/\/meircohenltd.com\/wc\/#website","url":"https:\/\/meircohenltd.com\/wc\/","name":"\u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05de\u05d5\u05e8\u05d5\u05ea \u05dc\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df \u05d1\u05e2&quot;\u05de","description":"\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df","publisher":{"@id":"https:\/\/meircohenltd.com\/wc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meircohenltd.com\/wc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"he-IL"},{"@type":"Organization","@id":"https:\/\/meircohenltd.com\/wc\/#organization","name":"\u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05de\u05d5\u05e8\u05d5\u05ea \u05dc\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df \u05d1\u05e2&quot;\u05de","url":"https:\/\/meircohenltd.com\/wc\/","logo":{"@type":"ImageObject","inLanguage":"he-IL","@id":"https:\/\/meircohenltd.com\/wc\/#\/schema\/logo\/image\/","url":"https:\/\/meircohenltd.com\/wp-content\/uploads\/2023\/07\/logo.svg","contentUrl":"https:\/\/meircohenltd.com\/wp-content\/uploads\/2023\/07\/logo.svg","width":605,"height":429,"caption":"\u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05de\u05d5\u05e8\u05d5\u05ea \u05dc\u05de\u05d0\u05d9\u05e8 \u05db\u05d4\u05df \u05d1\u05e2&quot;\u05de"},"image":{"@id":"https:\/\/meircohenltd.com\/wc\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/meircohenltd.com\/js\/wp-json\/wp\/v2\/product\/485257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meircohenltd.com\/js\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/meircohenltd.com\/js\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meircohenltd.com\/js\/wp-json\/wp\/v2\/media\/443919"}],"wp:attachment":[{"href":"https:\/\/meircohenltd.com\/js\/wp-json\/wp\/v2\/media?parent=485257"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/meircohenltd.com\/js\/wp-json\/wp\/v2\/product_brand?post=485257"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/meircohenltd.com\/js\/wp-json\/wp\/v2\/product_cat?post=485257"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/meircohenltd.com\/js\/wp-json\/wp\/v2\/product_tag?post=485257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}